{"id":18,"date":"2014-05-28T14:14:00","date_gmt":"2014-05-28T14:14:00","guid":{"rendered":"http:\/\/blog-nationa-lang-fr.arnaud-bernard.org\/index.php\/2014\/05\/28\/interview-aurelie-filippetti\/"},"modified":"2021-03-01T13:52:41","modified_gmt":"2021-03-01T12:52:41","slug":"interview-aurelie-filippetti","status":"publish","type":"post","link":"https:\/\/www.nationalisation-langues-de-france.net\/index.php\/2014\/05\/28\/interview-aurelie-filippetti\/","title":{"rendered":"Interview d&rsquo;Aur\u00e9lie Filippetti (D\u00e9p\u00eache du Midi, 14 mai 2014)"},"content":{"rendered":"<p><em>\u00a0\u00bbInterview d&rsquo;Aur\u00e9lie Filippetti, Ministre de la culture et de la communication, pour la D\u00e9p\u00eache du Midi le 14 mai 2014\u00a0\u00bb<\/em><\/p>\n<p><b>&#8211; Connaissez-vous le Forom des Langues de Toulouse ? Qu&rsquo;est-ce que cela vous inspire ?<br \/>\n<\/b>En vingt-deux ann\u00e9es d\u2019existence, le Forom s\u2019est forg\u00e9 une notori\u00e9t\u00e9 qui le voit essaimer partout en France, en Europe et jusqu\u2019\u00e0 Madagascar. La manifestation s\u2019est inscrite au fil du temps en bonne place parmi les rendez-vous importants de la diversit\u00e9 culturelle. Cela tient \u00e0 la valeur de l\u2019id\u00e9e m\u00eame de forum, magnifiquement adapt\u00e9e aux conditions d\u2019aujourd\u2019hui. En ouvrant la place du Capitole \u00e0 toutes les langues parl\u00e9es dans la ville, c\u2019est un espace d\u2019expression d\u00e9mocratique que nous offre chaque ann\u00e9e le Carrefour culturel Arnaud-Bernard. En t\u00e9moigne le sujet retenu cette ann\u00e9e : la langue et la culture fran\u00e7aises, notre langue et notre culture communes. Quelle place font-elles \u00e0 la diversit\u00e9 ? C\u2019est un d\u00e9bat r\u00e9current dans les m\u00e9dias et sur les r\u00e9seaux sociaux, mais quelle belle occasion de l\u2019aborder de vive voix, en pr\u00e9sence de sp\u00e9cialistes comme Alain Rey, sur la place publique !<\/p>\n<p><!--more--><br \/>\n<strong>&#8211; Quelle est la place, justement, que les langues r\u00e9gionales peuvent prendre dans la culture fran\u00e7aise ? Que pensez-vous de la proposition de cette \u00e9ducation minimum de tous les fran\u00e7ais \u00e0 toutes les langues \u00ab\u00a0r\u00e9gionales\u00a0\u00bb de France que le Carrefour Culturel Arnaud-Bernard ?<\/strong>Valoriser les langues r\u00e9gionales, c\u2019est lib\u00e9rer la parole, et d\u00e9multiplier les messages de notre pays dans tous les champs de la culture. Opposer le fran\u00e7ais et les langues de France est une d\u00e9marche obsol\u00e8te : la France est riche de sa diversit\u00e9 et de son patrimoine linguistique au contraire, l\u2019un des plus riches d\u2019Europe. Depuis toujours, les langues r\u00e9gionales ont nourri le fran\u00e7ais, qui en a tir\u00e9 une bonne part de son dynamisme. Offrir \u00e0 tous les jeunes Fran\u00e7ais une initiation \u00e0 la pluralit\u00e9 des langues m\u2019appara\u00eet comme une n\u00e9cessit\u00e9 \u00e9l\u00e9mentaire d\u2019\u00e9ducation. La loi sur la refondation de l\u2019\u00e9cole de la R\u00e9publique donne d\u2019ailleurs un point d\u2019appui \u00e0 cette initiative, en pr\u00e9cisant que les professeurs peuvent recourir aux langues r\u00e9gionales d\u00e8s lors qu\u2019ils en tireront profit pour leur enseignement, et que l\u2019exposition pr\u00e9coce \u00e0 une langue vivante est un facteur de progr\u00e8s en mati\u00e8re d\u2019apprentissage. A titre personnel, je pense que tous les enfants ont le droit de savoir qu\u2019\u00e0 aucun moment de notre histoire, on n\u2019a parl\u00e9 une seule langue dans notre pays. Jaur\u00e8s, dans un article de La D\u00e9p\u00eache en 1911, montrait tout l\u2019int\u00e9r\u00eat qu\u2019il y aurait \u00e0 ne pas ignorer le languedocien pour la culture du peuple.<\/p>\n<p><strong>&#8211; O\u00f9 en est le processus de ratification de la charte europ\u00e9enne ?<br \/>\n<\/strong>La ratification de la Charte europ\u00e9enne des langues r\u00e9gionales et minoritaires, sign\u00e9e par la France en 1999, est un engagement du Pr\u00e9sident de la R\u00e9publique. Vous savez qu\u2019elle pose une difficult\u00e9 constitutionnelle, dans la mesure o\u00f9 certaines de ses dispositions peuvent \u00eatre interpr\u00e9t\u00e9es comme contraires aux principes fondamentaux de la R\u00e9publique \u00e9nonc\u00e9s dans les articles 1 et 2 de la Constitution : \u00e9galit\u00e9 des citoyens devant la loi, unicit\u00e9 du peuple fran\u00e7ais, officialit\u00e9 du fran\u00e7ais. Afin de v\u00e9rifier qu\u2019une majorit\u00e9 parlementaire pouvait cependant se d\u00e9gager sur la ratification, le gouvernement a ouvert le d\u00e9bat au Parlement. Le texte qui a \u00e9t\u00e9 adopt\u00e9 \u00e0 une tr\u00e8s large majorit\u00e9 par l\u2019Assembl\u00e9e nationale le 28 janvier dernier prend soin de dissiper toute ambigu\u00eft\u00e9 sur le respect de nos principes constitutionnels fondamentaux. Ce vote a constitu\u00e9 une \u00e9tape importante : pour la premi\u00e8re fois, les \u00e9lus de la R\u00e9publique ont pu exprimer dans l\u2019h\u00e9micycle l\u2019apport des langues r\u00e9gionales \u00e0 notre richesse et diversit\u00e9 culturelles. Le travail doit se poursuivre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00bbInterview d&rsquo;Aur\u00e9lie Filippetti, Ministre de la culture et de la communication, pour la D\u00e9p\u00eache du Midi le 14 mai 2014\u00a0\u00bb __- Connaissez-vous le Forom des Langues de Toulouse ? Qu&rsquo;est-ce que cela vous inspire ?__%%% En vingt-deux ann\u00e9es d\u2019existence, le Forom s\u2019est forg\u00e9 une notori\u00e9t\u00e9 qui le voit essaimer partout en France, en Europe et jusqu\u2019\u00e0 Madagascar. La manifestation s\u2019est inscrite au fil du temps en bonne place parmi les rendez-vous importants de la diversit\u00e9 culturelle. Cela tient \u00e0 la valeur de l\u2019id\u00e9e m\u00eame de forum, magnifiquement adapt\u00e9e aux conditions d\u2019aujourd\u2019hui. En ouvrant la place du Capitole \u00e0 toutes les langues parl\u00e9es dans la ville, c\u2019est un espace d\u2019expression d\u00e9mocratique que nous offre chaque ann\u00e9e le Carrefour culturel Arnaud-Bernard. En t\u00e9moigne le sujet retenu cette ann\u00e9e  : la langue et la culture fran\u00e7aises, notre langue et notre culture communes. Quelle place font-elles \u00e0 la diversit\u00e9 ? C\u2019est un d\u00e9bat r\u00e9current dans les m\u00e9dias et sur les r\u00e9seaux sociaux, mais quelle belle occasion de l\u2019aborder de vive voix, en pr\u00e9sence de sp\u00e9cialistes comme Alain Rey, sur la place publique  !<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[4],"tags":[],"class_list":["post-18","post","type-post","status-publish","format-standard","hentry","category-contributions","entry"],"_links":{"self":[{"href":"https:\/\/www.nationalisation-langues-de-france.net\/index.php\/wp-json\/wp\/v2\/posts\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nationalisation-langues-de-france.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nationalisation-langues-de-france.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nationalisation-langues-de-france.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nationalisation-langues-de-france.net\/index.php\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":0,"href":"https:\/\/www.nationalisation-langues-de-france.net\/index.php\/wp-json\/wp\/v2\/posts\/18\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.nationalisation-langues-de-france.net\/index.php\/wp-json\/wp\/v2\/media?parent=18"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nationalisation-langues-de-france.net\/index.php\/wp-json\/wp\/v2\/categories?post=18"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nationalisation-langues-de-france.net\/index.php\/wp-json\/wp\/v2\/tags?post=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}